{"id":1163,"date":"2022-02-15T11:03:25","date_gmt":"2022-02-15T14:03:25","guid":{"rendered":"https:\/\/editoralandmark.com.br\/v2.0\/?p=1163"},"modified":"2022-02-15T11:03:25","modified_gmt":"2022-02-15T14:03:25","slug":"06-06-2013-o-grande-gatsby-de-f-scott-fitzgerald-no-jornal-diario-de-pernambuco","status":"publish","type":"post","link":"https:\/\/editoralandmark.com.br\/v2.0\/2022\/02\/15\/06-06-2013-o-grande-gatsby-de-f-scott-fitzgerald-no-jornal-diario-de-pernambuco\/","title":{"rendered":"06\/06\/2013 &#8211; O GRANDE GATSBY, DE F. SCOTT FITZGERALD, NO JORNAL DI\u00c1RIO DE PERNAMBUCO"},"content":{"rendered":"<p>&#8220;O Grande Gatsby \u00e9 relan\u00e7ado por editora<\/p>\n<p>Pegando carona no filme, Landmark e Leya colocam nas livrarias duas edi\u00e7\u00f5es do cl\u00e1ssico norte-americano<\/p>\n<p>A nova adapta\u00e7\u00e3o de O grande Gatsby, do escritor norte-americano F. Scott Fitzgerald (1896-1940), chega aos cinemas nesta sexta-feira (07), estrelado por Leonardo Dicaprio (Jay Gatsby), Carey Mulligan (Daisy Buchanan), Tobey Maguire (Nick Carraway) e Joel Edgerton (Tom Buchanan). Pegando carona no lan\u00e7amento do filme, as editoras Landmark e Leya colocam nas livrarias duas edi\u00e7\u00f5es do cl\u00e1ssico da literatura.<\/p>\n<p>A obra, que descreve a vida da alta sociedade norte-americana dos anos 1920, \u00e9 considerada um dos melhores romances de l\u00edngua inglesa do s\u00e9culo 20. A edi\u00e7\u00e3o da Landmark \u00e9 bil\u00edngue e em capa dura, com a mesma proposta visual do filme. J\u00e1 a editora Leya traz capa diferente, com padr\u00e3o verde. Ambas custam R$ 30.<\/p>\n<p>Por Fellipe Torres&#8221;JORNAL DI\u00c1RIO DE PERNAMBUCO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;O Grande Gatsby \u00e9 relan\u00e7ado por editora Pegando carona no filme, Landmark e Leya colocam nas livrarias duas edi\u00e7\u00f5es do cl\u00e1ssico norte-americano A nova adapta\u00e7\u00e3o de O grande Gatsby, do escritor norte-americano F. Scott Fitzgerald (1896-1940), chega aos cinemas nesta sexta-feira (07), estrelado por Leonardo Dicaprio (Jay Gatsby), Carey Mulligan (Daisy Buchanan), Tobey Maguire (Nick&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[54],"tags":[],"class_list":{"0":"post-1163","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"hentry","6":"category-54","8":"description-off"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/posts\/1163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/comments?post=1163"}],"version-history":[{"count":1,"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/posts\/1163\/revisions"}],"predecessor-version":[{"id":1164,"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/posts\/1163\/revisions\/1164"}],"wp:attachment":[{"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/media?parent=1163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/categories?post=1163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/editoralandmark.com.br\/v2.0\/wp-json\/wp\/v2\/tags?post=1163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}